{"id":696,"date":"2016-08-01T14:40:02","date_gmt":"2016-08-01T12:40:02","guid":{"rendered":"http:\/\/www.oiartzoikastola.eus\/nor-gara\/"},"modified":"2024-09-04T11:18:20","modified_gmt":"2024-09-04T09:18:20","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/www.oiartzoikastola.eus\/es\/nor-garen\/quienes-somos\/","title":{"rendered":"Qui\u00e9nes somos"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_half-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-6126cab7d8fab8d08143dd2dacdf673c av_one_half  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-lypqoj99-88e737d1148ab9e87785f57fcbc2471f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>ORGANIGRAMA<\/h3>\n<p>El gobierno y funcionamiento de Oiartzo Ikastola sigue la estructura del siguiente organigrama:<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-5ea7596238ed9f191e6b5e662093052f\">\n#top .hr.hr-invisible.av-av_hr-5ea7596238ed9f191e6b5e662093052f{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-av_hr-5ea7596238ed9f191e6b5e662093052f hr-invisible  avia-builder-el-2  el_after_av_textblock  el_before_av_image '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_image-3eb5cdc5201f4b1972bdf59787f0ec8f\">\n.avia-image-container.av-av_image-3eb5cdc5201f4b1972bdf59787f0ec8f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-av_image-3eb5cdc5201f4b1972bdf59787f0ec8f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-av_image-3eb5cdc5201f4b1972bdf59787f0ec8f av-styling- av-img-linked avia-align-center  avia-builder-el-3  el_after_av_hr  avia-builder-el-last '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1.png\" data-srcset=\"https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1.png 769w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-300x281.png 300w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-768x720.png 768w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-705x661.png 705w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-450x422.png 450w\" data-sizes=\"(max-width: 769px) 100vw, 769px\" class='avia_image '  aria-label='organigrama'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-689 avia-img-lazy-loading-not-689 avia_image ' src=\"https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1.png\" alt='' title='organigrama'  height=\"721\" width=\"769\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1.png 769w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-300x281.png 300w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-768x720.png 768w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-705x661.png 705w, https:\/\/www.oiartzoikastola.eus\/wp-content\/uploads\/2016\/08\/organigrama-1-450x422.png 450w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/><\/a><\/div><\/div><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_half-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-0aa7055fe62c3622faec82866afbaeb2 av_one_half  avia-builder-el-4  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-l8a583jp-16059cff515e07ad7c6f5429cfd47c14 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>EQUIPO DIRECTIVO<\/h3>\n<p>El equipo directivo est\u00e1 formado por la directora, el jefe de estudios y la orientadora. La funci\u00f3n principal de este equipo es coordinar la planificaci\u00f3n del centro e impulsar las actividades principales, siempre siguiendo los objetivos y directrices del Proyecto de la Ikastola.<\/p>\n<ul>\n<li>Directora: Olatz Mitxelena<\/li>\n<li>Jefe de estudios: Jon Xabin Urretabizkaia<\/li>\n<li>Orientadora: Ainhoa Gaztelumendi<\/li>\n<\/ul>\n<h3>CLAUSTRO<\/h3>\n<p>Siendo Oiartzo una Ikastola peque\u00f1a, el claustro tambi\u00e9n lo es, lo cual permite una cercan\u00eda con el o la estudiante y un seguimiento personalizado de cada uno.<\/p>\n<p>Para optimizar la coordinaci\u00f3n con Haurtzaro y Orereta Ikastolak, creadoras del proyecto de Oiartzo Ikastola, algunos profesores y profesoras de Oiartzo tambi\u00e9n pertenecen al claustro de Haurtzaro y\/o Orereta.<\/p>\n<h3>COMISI\u00d3N DE MADRES Y PADRES<\/h3>\n<p>La Comisi\u00f3n de Madres y Padres est\u00e1 formada por un representante de cada clase, y el resto de padres y madres tambi\u00e9n pueden tomar parte.<\/p>\n<p>La Comisi\u00f3n no tiene capacidad de decisi\u00f3n, pero puede hacer propuestas al Consejo Escolar.<\/p>\n<h3>CONSEJO ESCOLAR<\/h3>\n<p>El Consejo Escolar est\u00e1 formado por representantes del Patronato, representantes de la Comisi\u00f3n de Madres y Padres, representantes de la direcci\u00f3n, representantes del claustro y representantes de los y las alumnas.<\/p>\n<p>Su funci\u00f3n es hacer seguimiento a la marcha de la Ikastola, y dirigir sus propuestas a los \u00f3rganos de decisi\u00f3n correspondientes. B\u00e1sicamente su funci\u00f3n es organizativa, pero, en algunos asuntos, puede tomar decisiones.<\/p>\n<h3>PATRONATO<\/h3>\n<p>El Patronato de la fundaci\u00f3n, como titular de Oiartzo Batxilergo Ikastola, es el \u00f3rgano superior de decisi\u00f3n. Participan en \u00e9l miembros de las Haurtzaro y Orereta Ikastolak. Son cuatro los miembros con capacidad de decisi\u00f3n en el Patronato: dos de Orereta y otros dos de Haurtzaro.<\/p>\n<p>El Patronato es el \u00f3rgano con potestad de tomar las decisiones m\u00e1s importantes.<\/p>\n<\/div><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":823,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-696","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/pages\/696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/comments?post=696"}],"version-history":[{"count":19,"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/pages\/696\/revisions"}],"predecessor-version":[{"id":5869,"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/pages\/696\/revisions\/5869"}],"up":[{"embeddable":true,"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/pages\/823"}],"wp:attachment":[{"href":"https:\/\/www.oiartzoikastola.eus\/es\/wp-json\/wp\/v2\/media?parent=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}